{"id":21053,"date":"2023-07-27T10:10:20","date_gmt":"2023-07-27T08:10:20","guid":{"rendered":"https:\/\/sisgeo.com\/produkte\/ipi-in-place-inclinometers\/"},"modified":"2026-07-17T12:11:23","modified_gmt":"2026-07-17T10:11:23","slug":"ipi-in-place-inclinometers","status":"publish","type":"page","link":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/","title":{"rendered":"IPI In-Place-Neigungsmesser"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21053\" class=\"elementor elementor-21053 elementor-3884\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a63a93 e-flex e-con-boxed e-con e-parent\" data-id=\"7a63a93\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99defb4 elementor-widget elementor-widget-text-editor\" data-id=\"99defb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>IPI (In-Place Inclinometers) sind ein Inklinometersystem das immer dann im geotechnischen Monitoring zum Einsatz kommt, wenn eine hohe Messfrequenz und eine automatische Datenerfassung gefordert sind. IPI Sonden sind darauf ausgelegt horizontale Verschiebungen oder Deformationen von Boden oder Gestein in verschiedensten geotechnischen Szenarien zu messen. IPI Systeme bestehen aus einer Kette von IPI Sonden und werden deshalb auch Ketteninklinometer genannt. Sie sind weit verbreitet und werden z.B. zur \u00dcberwachung von tiefen Aush\u00fcben, Baugruben, H\u00e4ngen, St\u00fctzw\u00e4nden, Tunnelauffahrungen, Sch\u00fcttungen und anderen geotechnisch \u00fcberwachungsw\u00fcrdigen Objekten eingesetzt.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a09a03 elementor-widget elementor-widget-accordion\" data-id=\"8a09a03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1441\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1441\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"29\" height=\"16\" viewBox=\"0 0 29 16\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.25 0L14.375 13.038L1.5 0L0 1.5L14.4 15.9L28.749 1.5L27.25 0Z\" fill=\"#E4002B\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"29\" height=\"14\" viewBox=\"0 0 29 14\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.49902 13.1885L14.374 2.61651L27.249 13.1885L28.749 11.9722L14.349 0.295833L2.28882e-05 11.9722L1.49902 13.1885Z\" fill=\"#E4002B\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Mehr zum Thema<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1441\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1441\"><p>BH-Profile ist das g\u00e4ngigste IPI System. Es ist f\u00fcr vertikale und horizontale Messstellen geeignet. Das System wird in einer mit Inklinometerrohr ausgebauten Messstelle installiert. BH-Profile IPIs werden zu einer fortlaufenden Kette zusammengesetzt und in das Inklinometerrohr eingebracht. BH-Profile Ketteninklinometer sind ISO Standard 18674-3 konform.   <\/p>\n<p>MD-Profile Sonden sind f\u00fcr den Einsatz in glatten Rohren ohne F\u00fchrungsnuten mit 1,5\u201c oder 2\u201c Durchmesser gemacht, was zu einer Kostenersparnis bei Bohrung und eingesetztem Rohr f\u00fchrt. Die speziell f\u00fcr diesen Einsatzzweck konzipierten F\u00fchrungsteile sorgen f\u00fcr eine Sondenzentrierung \u00fcber die gesamte Kettenl\u00e4nge und garantieren so die Langzeitstabilit\u00e4t. <\/p>\n<p><span style=\"color: var( --e-global-color-text ); font-size: 1rem;\">Das&nbsp;<\/span><span style=\"color: var( --e-global-color-text ); font-size: 1rem;\">LT-Inclibus&nbsp;<\/span><span style=\"color: var( --e-global-color-text ); font-size: 1rem;\">Standardelement besteht aus einem 2m Glasfaserstab mit je zwei wasserdichten, 360\u00b0 kalbrierten Neigungsmessern im Abstand von 1m. Eine Konfiguration mit einem, oder sogar vier Neigungsmessern auf einem 2m Glasfaserstab ist auf Nachfrage m\u00f6glich. &nbsp;<\/span><span style=\"color: var( --e-global-color-text ); font-size: 1rem;\">Die St\u00e4be werden mit einer Kupplung mechanisch miteinander verbunden, die Sensoren werden per RS485 Digitalbus zu einer Kette verbunden. Die LT-Inclibus-Kette kann in einem Bohrloch, einem Graben oder einem Betonteil eingebaut werden. <\/span><\/p>\n<p>Als Erweiterung zum DEX Extensometer verf\u00fcgt das DEX-S Extenso-Inklinometer \u00fcber einen biaxialen Neigungssensor, sodass man dreidimensionale Informationen aus den Messstellen erh\u00e4lt. <\/p>\n<p>Weiterf\u00fchrende Informationen und Hilfestellungen bez\u00fcglich IPI (In-Place Inclinometers), bzw. Ketteninklinometer k\u00f6nnen in der ISO 18674-3 \u201cMeasurement of displacements across a line: Inclinometers\u201d gefunden werden.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a3ecd dce-posts-layout-default dce-col-4 dce-col-tablet-3 dce-col-mobile-1 dce-align-left elementor-widget elementor-widget-dce-dynamicposts-v2\" data-id=\"58a3ecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;style_items&quot;:&quot;default&quot;,&quot;grid_grid_type&quot;:&quot;flex&quot;}\" data-widget_type=\"dce-dynamicposts-v2.grid\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"dce-fix-background-loop dce-posts-container dce-posts dce-dynamic-posts-collection  dce-skin-grid dce-skin-grid-flex\">\n\t\t\t\t\t\t<div class=\"dce-posts-wrapper dce-wrapper-grid\">\n\t\t\t\n\t\t<article class=\"post-20539 page type-page status-publish has-post-thumbnail hentry category-bh-profile-in-place-inclinometers-de category-ipi-in-place-inclinometers-de dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"20539\" data-dce-post-index=\"0\">\n\t\t\t<div class=\"dce-post-block elementor-animation-grow\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-9ee1dae\"><a class=\"dce-post-image\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/bh-profile-in-place-inclinometers\/\"><figure  class=\"dce-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_inclinometers_borehole_profile_e5fb31d910011060e405d8f6b6542839.png\" class=\"\" alt=\"BH-Profile in-place Inclinometers\" srcset=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_inclinometers_borehole_profile_e5fb31d910011060e405d8f6b6542839.png 960w, https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_inclinometers_borehole_profile_e5fb31d910011060e405d8f6b6542839-300x169.png 300w, https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_inclinometers_borehole_profile_e5fb31d910011060e405d8f6b6542839-768x432.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-b433209\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/bh-profile-in-place-inclinometers\/\">BH-Profile in-place Inclinometers<\/a><\/h5><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-ef0e5ce\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/bh-profile-in-place-inclinometers\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-sm\" role=\"button\" >\n\t\t\t<div class=\"align-middle\"><span>Mehr erfahren<\/span><img decoding=\"async\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/05\/arrow_red.png\"><\/div>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-20569 page type-page status-publish has-post-thumbnail hentry category-ipi-in-place-inclinometers-de category-md-profile-array-de dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"20569\" data-dce-post-index=\"1\">\n\t\t\t<div class=\"dce-post-block elementor-animation-grow\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-9ee1dae\"><a class=\"dce-post-image\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/md-profile-system\/\"><figure  class=\"dce-img\"><img decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg\" class=\"\" alt=\"MD-Profile 360\u00b0 Ketteninklinometer\" srcset=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg 960w, https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products-300x169.jpg 300w, https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-b433209\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/md-profile-system\/\">MD-Profile 360\u00b0 Ketteninklinometer<\/a><\/h5><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-ef0e5ce\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/md-profile-system\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-sm\" role=\"button\" >\n\t\t\t<div class=\"align-middle\"><span>Mehr erfahren<\/span><img decoding=\"async\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/05\/arrow_red.png\"><\/div>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-20562 page type-page status-publish has-post-thumbnail hentry category-ipi-in-place-inclinometers-de category-lt-inclibus-de-2 category-lt-inclibus-de category-neigungsmesser dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"20562\" data-dce-post-index=\"2\">\n\t\t\t<div class=\"dce-post-block elementor-animation-grow\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-9ee1dae\"><a class=\"dce-post-image\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/360-lt-inclibus-array\/\"><figure  class=\"dce-img\"><img decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/0_LT-Inclibus-array-inclinometer.jpg\" class=\"\" alt=\"360\u00b0 LT-Inclibus array\" srcset=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/0_LT-Inclibus-array-inclinometer.jpg 960w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/0_LT-Inclibus-array-inclinometer-300x169.jpg 300w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/0_LT-Inclibus-array-inclinometer-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-b433209\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/360-lt-inclibus-array\/\">360\u00b0 LT-Inclibus array<\/a><\/h5><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-ef0e5ce\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/360-lt-inclibus-array\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-sm\" role=\"button\" >\n\t\t\t<div class=\"align-middle\"><span>Mehr erfahren<\/span><img decoding=\"async\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/05\/arrow_red.png\"><\/div>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-20555 page type-page status-publish has-post-thumbnail hentry category-horizontal-in-place-inclinometers-de category-ipi-in-place-inclinometers-de dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"20555\" data-dce-post-index=\"3\">\n\t\t\t<div class=\"dce-post-block elementor-animation-grow\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-9ee1dae\"><a class=\"dce-post-image\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/horizontal-in-place-inclinometers\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_horizontal_bh-profile_03e2bced30f9626ccdc4.png\" class=\"\" alt=\"Horizontal In Place Inclinometers\" srcset=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_horizontal_bh-profile_03e2bced30f9626ccdc4.png 960w, https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_horizontal_bh-profile_03e2bced30f9626ccdc4-300x169.png 300w, https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/0_sisgeo_horizontal_bh-profile_03e2bced30f9626ccdc4-768x432.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-b433209\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/horizontal-in-place-inclinometers\/\">Horizontal In Place Inclinometers<\/a><\/h5><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-ef0e5ce\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/horizontal-in-place-inclinometers\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-sm\" role=\"button\" >\n\t\t\t<div class=\"align-middle\"><span>Mehr erfahren<\/span><img decoding=\"async\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/05\/arrow_red.png\"><\/div>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-20576 page type-page status-publish has-post-thumbnail hentry category-analoges-ketteninklinometer category-ipi-in-place-inclinometers-de dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"20576\" data-dce-post-index=\"4\">\n\t\t\t<div class=\"dce-post-block elementor-animation-grow\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-9ee1dae\"><a class=\"dce-post-image\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/analoges-ketteninklinometer\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/in_place_inclinometers_0_57c5384e6f7c7a37.png\" class=\"\" alt=\"Analoges Ketteninklinometer\" srcset=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/in_place_inclinometers_0_57c5384e6f7c7a37.png 960w, https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/in_place_inclinometers_0_57c5384e6f7c7a37-300x169.png 300w, https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/08\/in_place_inclinometers_0_57c5384e6f7c7a37-768x432.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-b433209\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/analoges-ketteninklinometer\/\">Analoges Ketteninklinometer<\/a><\/h5><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-ef0e5ce\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/analoges-ketteninklinometer\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-sm\" role=\"button\" >\n\t\t\t<div class=\"align-middle\"><span>Mehr erfahren<\/span><img decoding=\"async\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/05\/arrow_red.png\"><\/div>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-20546 page type-page status-publish has-post-thumbnail hentry category-dex-extensometer-und-dex-s-extenso-inklinometer category-dex-extensometer-und-dex-s-extenso-inklinometers category-dehnungsmessstreifen category-ipi-in-place-inclinometers-de dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"20546\" data-dce-post-index=\"5\">\n\t\t\t<div class=\"dce-post-block elementor-animation-grow\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-9ee1dae\"><a class=\"dce-post-image\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/dex-s-3d-extenso-inclinometer\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-scaled.jpg\" class=\"\" alt=\"DEX-S 3D extenso-inclinometer\" srcset=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-scaled.jpg 2560w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-300x169.jpg 300w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-1024x576.jpg 1024w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-768x432.jpg 768w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-1536x864.jpg 1536w, https:\/\/sisgeo.com\/wp-content\/uploads\/2024\/10\/dex_extenso-inclinometer-ipi-sisgeo0-2048x1152.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-b433209\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/dex-s-3d-extenso-inclinometer\/\">DEX-S 3D extenso-inclinometer<\/a><\/h5><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-ef0e5ce\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/dex-s-3d-extenso-inclinometer\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-sm\" role=\"button\" >\n\t\t\t<div class=\"align-middle\"><span>Mehr erfahren<\/span><img decoding=\"async\" src=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2023\/05\/arrow_red.png\"><\/div>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>IPI (In-Place Inclinometers) sind ein Inklinometersystem das immer dann im geotechnischen Monitoring zum Einsatz kommt, wenn eine hohe Messfrequenz und eine automatische Datenerfassung gefordert sind. IPI Sonden sind darauf ausgelegt horizontale Verschiebungen oder Deformationen von Boden oder Gestein in verschiedensten geotechnischen Szenarien zu messen. IPI Systeme bestehen aus einer Kette von IPI Sonden und werden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28429,"parent":20241,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[215],"tags":[],"class_list":["post-21053","page","type-page","status-publish","has-post-thumbnail","hentry","category-products-de-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IPI In-Place-Neigungsmesser - Sisgeo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IPI In-Place-Neigungsmesser\" \/>\n<meta property=\"og:description\" content=\"IPI (In-Place Inclinometers) sind ein Inklinometersystem das immer dann im geotechnischen Monitoring zum Einsatz kommt, wenn eine hohe Messfrequenz und eine automatische Datenerfassung gefordert sind. IPI Sonden sind darauf ausgelegt horizontale Verschiebungen oder Deformationen von Boden oder Gestein in verschiedensten geotechnischen Szenarien zu messen. IPI Systeme bestehen aus einer Kette von IPI Sonden und werden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/\" \/>\n<meta property=\"og:site_name\" content=\"Sisgeo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-17T10:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/\",\"url\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/\",\"name\":\"IPI In-Place-Neigungsmesser - Sisgeo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sisgeo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/md-profile-inclinometers-sisgeo-products.jpg\",\"datePublished\":\"2023-07-27T08:10:20+00:00\",\"dateModified\":\"2026-07-17T10:11:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sisgeo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/md-profile-inclinometers-sisgeo-products.jpg\",\"contentUrl\":\"https:\\\/\\\/sisgeo.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/md-profile-inclinometers-sisgeo-products.jpg\",\"width\":960,\"height\":540,\"caption\":\"MD-Profile 360\u00b0 Ketteninklinometer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/ipi-in-place-inclinometers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/geotechnische-und-strukturelle-instrumentierung-fuer-shm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IPI In-Place-Neigungsmesser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/\",\"name\":\"Sisgeo\",\"description\":\"Inclined to improvement\",\"publisher\":{\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/#organization\",\"name\":\"Sisgeo S.r.l.\",\"url\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sisgeodev.pipehosting.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-RGB.png\",\"contentUrl\":\"https:\\\/\\\/sisgeodev.pipehosting.it\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-RGB.png\",\"width\":205,\"height\":97,\"caption\":\"Sisgeo S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/sisgeo.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IPI In-Place-Neigungsmesser - Sisgeo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/","og_locale":"de_DE","og_type":"article","og_title":"IPI In-Place-Neigungsmesser","og_description":"IPI (In-Place Inclinometers) sind ein Inklinometersystem das immer dann im geotechnischen Monitoring zum Einsatz kommt, wenn eine hohe Messfrequenz und eine automatische Datenerfassung gefordert sind. IPI Sonden sind darauf ausgelegt horizontale Verschiebungen oder Deformationen von Boden oder Gestein in verschiedensten geotechnischen Szenarien zu messen. IPI Systeme bestehen aus einer Kette von IPI Sonden und werden [&hellip;]","og_url":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/","og_site_name":"Sisgeo","article_modified_time":"2026-07-17T10:11:23+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/","url":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/","name":"IPI In-Place-Neigungsmesser - Sisgeo","isPartOf":{"@id":"https:\/\/sisgeo.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/#primaryimage"},"image":{"@id":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/#primaryimage"},"thumbnailUrl":"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg","datePublished":"2023-07-27T08:10:20+00:00","dateModified":"2026-07-17T10:11:23+00:00","breadcrumb":{"@id":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/#primaryimage","url":"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg","contentUrl":"https:\/\/sisgeo.com\/wp-content\/uploads\/2025\/05\/md-profile-inclinometers-sisgeo-products.jpg","width":960,"height":540,"caption":"MD-Profile 360\u00b0 Ketteninklinometer"},{"@type":"BreadcrumbList","@id":"https:\/\/sisgeo.com\/de\/produkte\/ipi-in-place-inclinometers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sisgeo.com\/de\/geotechnische-und-strukturelle-instrumentierung-fuer-shm\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/sisgeo.com\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"IPI In-Place-Neigungsmesser"}]},{"@type":"WebSite","@id":"https:\/\/sisgeo.com\/de\/#website","url":"https:\/\/sisgeo.com\/de\/","name":"Sisgeo","description":"Inclined to improvement","publisher":{"@id":"https:\/\/sisgeo.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sisgeo.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sisgeo.com\/de\/#organization","name":"Sisgeo S.r.l.","url":"https:\/\/sisgeo.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sisgeo.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/sisgeodev.pipehosting.it\/wp-content\/uploads\/2023\/06\/logo-RGB.png","contentUrl":"https:\/\/sisgeodev.pipehosting.it\/wp-content\/uploads\/2023\/06\/logo-RGB.png","width":205,"height":97,"caption":"Sisgeo S.r.l."},"image":{"@id":"https:\/\/sisgeo.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/pages\/21053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/comments?post=21053"}],"version-history":[{"count":12,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/pages\/21053\/revisions"}],"predecessor-version":[{"id":31744,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/pages\/21053\/revisions\/31744"}],"up":[{"embeddable":true,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/pages\/20241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/media\/28429"}],"wp:attachment":[{"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/media?parent=21053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/categories?post=21053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sisgeo.com\/de\/wp-json\/wp\/v2\/tags?post=21053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}